{"id":1662,"count":37,"description":"","link":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/","name":"Kartell","slug":"kartell","taxonomy":"product_brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oboemuebles.com\/en\/brand\/kartell\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oboemuebles.com\/en\/brand\/kartell\/\" \/>\n<meta property=\"og:site_name\" content=\"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/brand\\\/kartell\\\/\",\"url\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/brand\\\/kartell\\\/\",\"name\":\"Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/brand\\\/kartell\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/brand\\\/kartell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kartell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/\",\"name\":\"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella\",\"description\":\"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oboemuebles.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/","og_locale":"en_US","og_type":"article","og_title":"Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","og_url":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/","og_site_name":"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/","url":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/","name":"Kartell archivos - Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","isPartOf":{"@id":"https:\/\/oboemuebles.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/oboemuebles.com\/en\/brand\/kartell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oboemuebles.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Kartell"}]},{"@type":"WebSite","@id":"https:\/\/oboemuebles.com\/en\/#website","url":"https:\/\/oboemuebles.com\/en\/","name":"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","description":"Oboe Muebles - Tienda de muebles en M\u00e1laga y Marbella","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oboemuebles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/oboemuebles.com\/en\/wp-json\/wp\/v2\/product_brand\/1662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oboemuebles.com\/en\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/oboemuebles.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/oboemuebles.com\/en\/wp-json\/wp\/v2\/product?product_brand=1662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}